{"id":18675,"count":2,"description":"","link":"https:\/\/essentiallypop.com\/epop\/tag\/give-you-up\/","name":"Give You Up","slug":"give-you-up","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/essentiallypop.com\/epop\/wp-json\/wp\/v2\/tags\/18675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/essentiallypop.com\/epop\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/essentiallypop.com\/epop\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/essentiallypop.com\/epop\/wp-json\/wp\/v2\/posts?tags=18675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}