{"id":14461,"count":1,"description":"","link":"https:\/\/essentiallypop.com\/epop\/tag\/scorsese\/","name":"Scorsese","slug":"scorsese","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/essentiallypop.com\/epop\/wp-json\/wp\/v2\/tags\/14461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/essentiallypop.com\/epop\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/essentiallypop.com\/epop\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/essentiallypop.com\/epop\/wp-json\/wp\/v2\/posts?tags=14461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}